{"id":5125,"date":"2020-09-27T15:36:55","date_gmt":"2020-09-27T14:36:55","guid":{"rendered":"https:\/\/controlar.com\/wp-content\/uploads\/2020\/09\/AAL_1.jpg"},"modified":"2020-09-27T15:36:55","modified_gmt":"2020-09-27T14:36:55","slug":"created-with-gimp-19-3","status":"inherit","type":"attachment","link":"https:\/\/controlar.com\/es-mx\/areas-de-negocio\/sistemas-de-automatizacion\/linea-automatica-de-montaje\/created-with-gimp-19-3\/","title":{"rendered":"Created with GIMP"},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"class_list":["post-5125","attachment","type-attachment","status-inherit"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Created with GIMP\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Andr\u00e9 Henriques\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/controlar.com\/es-mx\/areas-de-negocio\/sistemas-de-automatizacion\/linea-automatica-de-montaje\/created-with-gimp-19-3\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/controlar.com\\\/es-mx\\\/areas-de-negocio\\\/sistemas-de-automatizacion\\\/linea-automatica-de-montaje\\\/created-with-gimp-19-3\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/controlar.com\\\/es-mx\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/controlar.com\\\/es-mx\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/controlar.com\\\/es-mx\\\/areas-de-negocio\\\/sistemas-de-automatizacion\\\/linea-automatica-de-montaje\\\/created-with-gimp-19-3\\\/#listItem\",\"name\":\"Created with GIMP\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/controlar.com\\\/es-mx\\\/areas-de-negocio\\\/sistemas-de-automatizacion\\\/linea-automatica-de-montaje\\\/created-with-gimp-19-3\\\/#listItem\",\"position\":2,\"name\":\"Created with GIMP\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/controlar.com\\\/es-mx\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/controlar.com\\\/es-mx\\\/areas-de-negocio\\\/sistemas-de-automatizacion\\\/linea-automatica-de-montaje\\\/created-with-gimp-19-3\\\/#itempage\",\"url\":\"https:\\\/\\\/controlar.com\\\/es-mx\\\/areas-de-negocio\\\/sistemas-de-automatizacion\\\/linea-automatica-de-montaje\\\/created-with-gimp-19-3\\\/\",\"name\":\"Created with GIMP | Controlar\",\"description\":\"Created with GIMP\",\"inLanguage\":\"es-MX\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/controlar.com\\\/es-mx\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/controlar.com\\\/es-mx\\\/areas-de-negocio\\\/sistemas-de-automatizacion\\\/linea-automatica-de-montaje\\\/created-with-gimp-19-3\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/controlar.com\\\/es-mx\\\/author\\\/mastertwbananas\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/controlar.com\\\/es-mx\\\/author\\\/mastertwbananas\\\/#author\"},\"datePublished\":\"2020-09-27T15:36:55+00:00\",\"dateModified\":\"2020-09-27T15:36:55+00:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/controlar.com\\\/es-mx\\\/#organization\",\"name\":\"Controlar Innovating Industry\",\"url\":\"https:\\\/\\\/controlar.com\\\/es-mx\\\/\",\"telephone\":\"+351 225 898 410\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/controlar.com\\\/es-mx\\\/author\\\/mastertwbananas\\\/#author\",\"url\":\"https:\\\/\\\/controlar.com\\\/es-mx\\\/author\\\/mastertwbananas\\\/\",\"name\":\"Andr\\u00e9 Henriques\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/controlar.com\\\/es-mx\\\/areas-de-negocio\\\/sistemas-de-automatizacion\\\/linea-automatica-de-montaje\\\/created-with-gimp-19-3\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8fb155a562333167098eb619cdcf1c40f86d7da94f5cc79863e735f4113aeefb?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Andr\\u00e9 Henriques\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/controlar.com\\\/es-mx\\\/#website\",\"url\":\"https:\\\/\\\/controlar.com\\\/es-mx\\\/\",\"name\":\"Controlar\",\"inLanguage\":\"es-MX\",\"publisher\":{\"@id\":\"https:\\\/\\\/controlar.com\\\/es-mx\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Created with GIMP | Controlar","description":"Created with GIMP","canonical_url":"https:\/\/controlar.com\/es-mx\/areas-de-negocio\/sistemas-de-automatizacion\/linea-automatica-de-montaje\/created-with-gimp-19-3\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/controlar.com\/es-mx\/areas-de-negocio\/sistemas-de-automatizacion\/linea-automatica-de-montaje\/created-with-gimp-19-3\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/controlar.com\/es-mx\/#listItem","position":1,"name":"Home","item":"https:\/\/controlar.com\/es-mx\/","nextItem":{"@type":"ListItem","@id":"https:\/\/controlar.com\/es-mx\/areas-de-negocio\/sistemas-de-automatizacion\/linea-automatica-de-montaje\/created-with-gimp-19-3\/#listItem","name":"Created with GIMP"}},{"@type":"ListItem","@id":"https:\/\/controlar.com\/es-mx\/areas-de-negocio\/sistemas-de-automatizacion\/linea-automatica-de-montaje\/created-with-gimp-19-3\/#listItem","position":2,"name":"Created with GIMP","previousItem":{"@type":"ListItem","@id":"https:\/\/controlar.com\/es-mx\/#listItem","name":"Home"}}]},{"@type":"ItemPage","@id":"https:\/\/controlar.com\/es-mx\/areas-de-negocio\/sistemas-de-automatizacion\/linea-automatica-de-montaje\/created-with-gimp-19-3\/#itempage","url":"https:\/\/controlar.com\/es-mx\/areas-de-negocio\/sistemas-de-automatizacion\/linea-automatica-de-montaje\/created-with-gimp-19-3\/","name":"Created with GIMP | Controlar","description":"Created with GIMP","inLanguage":"es-MX","isPartOf":{"@id":"https:\/\/controlar.com\/es-mx\/#website"},"breadcrumb":{"@id":"https:\/\/controlar.com\/es-mx\/areas-de-negocio\/sistemas-de-automatizacion\/linea-automatica-de-montaje\/created-with-gimp-19-3\/#breadcrumblist"},"author":{"@id":"https:\/\/controlar.com\/es-mx\/author\/mastertwbananas\/#author"},"creator":{"@id":"https:\/\/controlar.com\/es-mx\/author\/mastertwbananas\/#author"},"datePublished":"2020-09-27T15:36:55+00:00","dateModified":"2020-09-27T15:36:55+00:00"},{"@type":"Organization","@id":"https:\/\/controlar.com\/es-mx\/#organization","name":"Controlar Innovating Industry","url":"https:\/\/controlar.com\/es-mx\/","telephone":"+351 225 898 410"},{"@type":"Person","@id":"https:\/\/controlar.com\/es-mx\/author\/mastertwbananas\/#author","url":"https:\/\/controlar.com\/es-mx\/author\/mastertwbananas\/","name":"Andr\u00e9 Henriques","image":{"@type":"ImageObject","@id":"https:\/\/controlar.com\/es-mx\/areas-de-negocio\/sistemas-de-automatizacion\/linea-automatica-de-montaje\/created-with-gimp-19-3\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/8fb155a562333167098eb619cdcf1c40f86d7da94f5cc79863e735f4113aeefb?s=96&d=mm&r=g","width":96,"height":96,"caption":"Andr\u00e9 Henriques"}},{"@type":"WebSite","@id":"https:\/\/controlar.com\/es-mx\/#website","url":"https:\/\/controlar.com\/es-mx\/","name":"Controlar","inLanguage":"es-MX","publisher":{"@id":"https:\/\/controlar.com\/es-mx\/#organization"}}]}},"aioseo_meta_data":{"post_id":"5125","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-01-06 17:13:10","updated":"2025-06-11 10:56:26","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/controlar.com\/es-mx\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCreated with GIMP\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/controlar.com\/es-mx\/"},{"label":"Created with GIMP","link":"https:\/\/controlar.com\/es-mx\/areas-de-negocio\/sistemas-de-automatizacion\/linea-automatica-de-montaje\/created-with-gimp-19-3\/"}],"smush":{"stats":{"time":0.43000000000000005,"bytes":4844,"percent":5.59,"size_before":86677,"size_after":81833,"lossy":1,"keep_exif":0,"api_version":"1.0"},"sizes":{"thumbnail":{"time":0.06,"bytes":444,"percent":6.37,"size_before":6969,"size_after":6525},"nectar_small_square":{"time":0.05,"bytes":408,"percent":6.45,"size_before":6322,"size_after":5914},"medium":{"time":0.09,"bytes":912,"percent":5.29,"size_before":17241,"size_after":16329},"regular_small":{"time":0.04,"bytes":1473,"percent":5.6,"size_before":26281,"size_after":24808},"portfolio-thumb_small":{"time":0.11,"bytes":1315,"percent":5.07,"size_before":25917,"size_after":24602},"portfolio-widget":{"time":0.08,"bytes":292,"percent":7.4,"size_before":3947,"size_after":3655}}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/controlar.com\/wp-content\/uploads\/2020\/09\/AAL_1.jpg'><img decoding=\"async\" width=\"300\" height=\"225\" data-src=\"https:\/\/controlar.com\/wp-content\/uploads\/2020\/09\/AAL_1-300x225.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" data-srcset=\"https:\/\/controlar.com\/wp-content\/uploads\/2020\/09\/AAL_1-300x225.jpg 300w, https:\/\/controlar.com\/wp-content\/uploads\/2020\/09\/AAL_1.jpg 400w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Created with GIMP<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":400,"height":300,"file":"2020\/09\/AAL_1.jpg","sizes":{"medium":{"file":"AAL_1-300x225.jpg","width":300,"height":225,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/controlar.com\/wp-content\/uploads\/2020\/09\/AAL_1-300x225.jpg"},"thumbnail":{"file":"AAL_1-150x150.jpg","width":150,"height":150,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/controlar.com\/wp-content\/uploads\/2020\/09\/AAL_1-150x150.jpg"},"portfolio-thumb_small":{"file":"AAL_1-400x269.jpg","width":400,"height":269,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/controlar.com\/wp-content\/uploads\/2020\/09\/AAL_1-400x269.jpg"},"portfolio-widget":{"file":"AAL_1-100x100.jpg","width":100,"height":100,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/controlar.com\/wp-content\/uploads\/2020\/09\/AAL_1-100x100.jpg"},"nectar_small_square":{"file":"AAL_1-140x140.jpg","width":140,"height":140,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/controlar.com\/wp-content\/uploads\/2020\/09\/AAL_1-140x140.jpg"},"regular_small":{"file":"AAL_1-350x300.jpg","width":350,"height":300,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/controlar.com\/wp-content\/uploads\/2020\/09\/AAL_1-350x300.jpg"},"full":{"file":"AAL_1.jpg","width":400,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/controlar.com\/wp-content\/uploads\/2020\/09\/AAL_1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"Created with GIMP","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"Created with GIMP","orientation":"0","keywords":[]},"filesize":339059},"post":5806,"source_url":"https:\/\/controlar.com\/wp-content\/uploads\/2020\/09\/AAL_1.jpg","filename":"AAL_1.jpg","filesize":339059,"_links":{"self":[{"href":"https:\/\/controlar.com\/es-mx\/wp-json\/wp\/v2\/media\/5125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/controlar.com\/es-mx\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/controlar.com\/es-mx\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/controlar.com\/es-mx\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/controlar.com\/es-mx\/wp-json\/wp\/v2\/comments?post=5125"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":5806,"href":"https:\/\/controlar.com\/es-mx\/wp-json\/wp\/v2\/pages\/5806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}